﻿{"id":112237,"date":"2026-03-19T10:45:37","date_gmt":"2026-03-19T16:45:37","guid":{"rendered":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/?p=112237"},"modified":"2026-03-25T12:10:29","modified_gmt":"2026-03-25T18:10:29","slug":"banco-industrial-y-bid-invest-amplian-apoyo-a-mipymes-y-proyectos-sostenibles-con-financiamiento-de-us133-millones","status":"publish","type":"post","link":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/medios-y-prensa\/banco-industrial-y-bid-invest-amplian-apoyo-a-mipymes-y-proyectos-sostenibles-con-financiamiento-de-us133-millones\/","title":{"rendered":"Banco Industrial y BID Invest ampl\u00edan apoyo a mipymes y proyectos sostenibles con financiamiento de US$133 millones"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]En el marco de las Reuniones Anuales del Grupo BID celebradas en Paraguay, Banco Industrial y BID Invest formalizaron un acuerdo de financiamiento por un total de US$133 millones, destinado a profundizar el desarrollo sostenible y fortalecer el tejido empresarial de Guatemala, con foco en las micro, peque\u00f1as y medianas empresas.<br \/>\nEste financiamiento permitir\u00e1 a Banco Industrial ampliar su oferta crediticia a sectores que generan el 77% del empleo en Guatemala, brindando un apoyo particular a mujeres emprendedoras y a la ejecuci\u00f3n de proyectos con impacto ambiental y social.<br \/>\nEn la firma del acuerdo participaron Luis Prado, gerente de la Divisi\u00f3n Banca Internacional de Bi y Jos\u00e9 Javier Jo, vicepresidente de Corresponsal\u00eda y Financiamiento Internacional de Bi, quienes destacaron que esta alianza refuerza el posicionamiento de la instituci\u00f3n como el banco l\u00edder de Guatemala y un referente de confianza a nivel internacional.<\/p>\n<h3>Impacto estrat\u00e9gico y regional<\/h3>\n<p>Adem\u00e1s del componente financiero, el acuerdo incluye asistencia t\u00e9cnica especializada por parte de BID Invest para la gesti\u00f3n de riesgos ambientales y la segmentaci\u00f3n de carteras sostenibles, alineando las operaciones del banco con los m\u00e1s altos est\u00e1ndares internacionales.<br \/>\nSe trata de un nuevo hito en la promoci\u00f3n de la salud financiera, que apunta al fortalecimiento del sistema financiero local y ratifica el inter\u00e9s de Bi en promover el desarrollo integral de las comunidades y su gente, reafirmando su compromiso de ser un motor de innovaci\u00f3n y estabilidad para el sistema financiero centroamericano.<br \/>\nEste nuevo paso reafirma la visi\u00f3n de Corporaci\u00f3n Bi de ser un catalizador del desarrollo sostenible, la inclusi\u00f3n financiera y la prosperidad compartida. La instituci\u00f3n renueva su compromiso de fortalecer el tejido social y acompa\u00f1ar el crecimiento econ\u00f3mico del pa\u00eds y la regi\u00f3n, impulsando iniciativas que mejoran la calidad de vida de las comunidades. En esta alianza, Bi y BID Invest encuentran un punto de convergencia para financiar empresas y proyectos con impacto econ\u00f3mico, social y ambiental que aceleren el desarrollo sostenible regional.[\/vc_column_text][vc_row_inner][vc_column_inner][vc_gallery interval=&#8221;3&#8243; images=&#8221;112265,112266,112267,112268,112269,112270,112271&#8243; img_size=&#8221;full&#8221; css=&#8221;&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Bi y BID Invest acuerdan US$133 millones para apoyar a MIPYMES, mujeres emprendedoras y proyectos con impacto ambiental y social.<\/p>\n","protected":false},"author":55,"featured_media":112271,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[191,376],"tags":[],"class_list":["post-112237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desarrollo","category-medios-y-prensa"],"_links":{"self":[{"href":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/wp-json\/wp\/v2\/posts\/112237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/wp-json\/wp\/v2\/comments?post=112237"}],"version-history":[{"count":4,"href":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/wp-json\/wp\/v2\/posts\/112237\/revisions"}],"predecessor-version":[{"id":113066,"href":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/wp-json\/wp\/v2\/posts\/112237\/revisions\/113066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/wp-json\/wp\/v2\/media\/112271"}],"wp:attachment":[{"href":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/wp-json\/wp\/v2\/media?parent=112237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/wp-json\/wp\/v2\/categories?post=112237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corporacionbi.com\/gt\/bancoindustrial\/wp-json\/wp\/v2\/tags?post=112237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}